{"id":4295,"date":"2019-09-04T17:25:00","date_gmt":"2019-09-04T15:25:00","guid":{"rendered":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/?p=4295"},"modified":"2019-12-11T19:05:00","modified_gmt":"2019-12-11T17:05:00","slug":"koerpersprache-im-bewerbungsgespraech","status":"publish","type":"post","link":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/koerpersprache-im-bewerbungsgespraech\/","title":{"rendered":"K\u00f6rpersprache im Bewerbungsgespr\u00e4ch: Unmittelbar und authentisch"},"content":{"rendered":"<p>Bis zu 95 Prozent unserer Glaubw\u00fcrdigkeit macht die K\u00f6rpersprache aus: Gestik und Haltung entscheiden nicht nur \u00fcber den ersten Eindruck im privaten Aufeinandertreffen &#8211; man sollte auch auf die <strong>K\u00f6rpersprache im Bewerbungsgespr\u00e4ch<\/strong> achten. Und nur wer seinen Inhalten positiv gegen\u00fcbersteht, kann diese auch \u00fcberzeugend pr\u00e4sentieren. Mit diesen <strong>K\u00f6rpersprache-Tricks<\/strong> rockt man als Bewerber das <a href=\"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/tricks-vorstellungsgespraech\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vorstellungsgespr\u00e4ch<\/a>.<\/p>\n<h2>Positive K\u00f6rpersprache im Bewerbungsgespr\u00e4ch: kongruent und authentisch<\/h2>\n<p>\u201e<em>Irritierend wirken Sie, wenn Sie Begeisterung heucheln, wo keine ist. Dann verr\u00e4t die K\u00f6rpersprache, was Sie wirklich denken<\/em>\u201c, wei\u00df Rhetoriktrainer Peter Flume. Sprache und K\u00f6rpersprache geh\u00f6ren zusammen, so der Redner aus N\u00fcrtingen.\u00a0Die K\u00f6rpersprache im Bewerbungsgespr\u00e4ch muss kongruent sein, um authentisch zu wirken. Ansonsten lieber skeptisch bleiben und das auch zugeben. Oder sich gezielt Punkte am potenziellen Arbeitgeber oder der neuen Stelle herauszupicken, mit denen man einverstanden ist. Legt der Bewerber dann seinen Gespr\u00e4chsschwerpunkt auf diese Aspekte, kann er besser \u00fcberzeugen.<\/p>\n<blockquote><p>Psychologen nennen das &#8222;assoziiert sein&#8220;.<\/p><\/blockquote>\n<h2>\u00dcberzeugend mit passenden\u00a0Gesten<\/h2>\n<figure id=\"attachment_4299\" aria-describedby=\"caption-attachment-4299\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" class=\"wp-image-4299\" src=\"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/09\/FLUM.png\" alt=\"\" width=\"300\" height=\"355\" srcset=\"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/09\/FLUM.png 346w, https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/09\/FLUM-253x300.png 253w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-4299\" class=\"wp-caption-text\">Offene Gesten oberhalb der G\u00fcrtellinie verst\u00e4rken das Gesprochene. (FOTO: Flume)<\/figcaption><\/figure>\n<p>Grunds\u00e4tzlich wirkt der Sprecher dann am \u00fcberzeugendsten, wenn er seine Aussagen mit passenden Geb\u00e4rden unterstreicht. Spricht er von Synergieeffekten, sind Handbewegungen, die ein Verzahnen oder Zusammenf\u00fchren andeuten, ideal. Wer von zeitlichen Abl\u00e4ufen oder Entwicklungen redet, sollte mit der Hand eine ruhige, klare Geste in der Waagrechten durchf\u00fchren. Das verweist auf einen Zeitstrahl oder eine Dauer. Sinnvoll ist au\u00dferdem, eine Geste auszuf\u00fchren und f\u00fcr eine Sekunde zu halten oder stehen zu lassen. Das f\u00fchrt zus\u00e4tzlich zu einer Pause und bringt Ruhe ins Gespr\u00e4ch. Die erzeugte Unterbrechung verst\u00e4rkt die Wirkung des zuletzt gesprochenen Satzes. Einen schwachen Inhalt mit einer \u00fcberzeugenden K\u00f6rpersprache \u00fcberdecken, k\u00f6nne man jedoch nicht, so der Rhetoriker. Auch hier gilt die Regel der Kongruenz: Sprache und K\u00f6rpersprache geh\u00f6ren zusammen und werden vom Betrachter nicht einzeln wahrgenommen. Mit echten Emotionen und Gesten steckt der Redner seine Gespr\u00e4chspartner regelrecht an.<\/p>\n<h2>Gro\u00dfe Gesten f\u00fcr das gro\u00dfe Publikum<\/h2>\n<p>F\u00fcr eine \u00fcberzeugende Rede sind pers\u00f6nliche Charakterz\u00fcge nicht ausschlaggebend: \u201e<em>Zwar werden Introvertierte ihre Gestik sparsamer, oder kleiner einsetzen, aber auch sie \u00fcberzeugen durch authentische Bewegungen<\/em>\u201c, wei\u00df Flume. Irritierend wirken offene Gesten jedoch dann, wenn sie unterhalb der G\u00fcrtellinie ausgef\u00fchrt werden. Dann muss der Betrachter, der intuitiv in die Augen des Gegen\u00fcbers schaut, zwischen zu niedrigen Gesten und dem Blickkontakt wechseln. Das ist auf Dauer zu anstrengend und der Bewerber verliert die Aufmerksamkeit seiner Gespr\u00e4chspartner.<\/p>\n<h2><img loading=\"lazy\" class=\"alignleft size-full wp-image-3879\" src=\"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/06\/lebenslauf-bewerbung-als-ingenieur-vorgaben.png\" alt=\"Bewerbung als Ingenieur, Lebenslauf Ingenieur Vorgaben\" width=\"397\" height=\"754\" srcset=\"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/06\/lebenslauf-bewerbung-als-ingenieur-vorgaben.png 397w, https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-content\/uploads\/2017\/06\/lebenslauf-bewerbung-als-ingenieur-vorgaben-158x300.png 158w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/>Augenkontakt kommt beim Gegen\u00fcber besser an<\/h2>\n<p>Neben den gezielt eingesetzten Handbewegungen spielt der Augenkontakt bei der K\u00f6rpersprache im Bewerbungsgespr\u00e4ch eine gro\u00dfe Rolle: \u201e<em>Halten Sie verbindlichen Blick zum Publikum und verstecken sich nicht hinter Zetteln oder Power Point<\/em>\u201c, empfiehlt Flume, der seit 25 Jahren Kommunikationstechniken lehrt. Menschen, die uns beim Gespr\u00e4ch nicht in die Augen schauen, wirken unsicher oder als h\u00e4tten Sie etwas zu verbergen. Auf keinen Fall transportiert ein unsteter Blick Selbstsicherheit und \u00dcberzeugungskraft. Stattdessen kann ein Redner seine Zuh\u00f6rer mit Blickkontakt an sich binden und die Aufmerksamkeitsspanne erh\u00f6hen.<\/p>\n<h2>K\u00f6rpersprache im Bewerbungsgespr\u00e4ch: \u00dcben und den ersten Eindruck nicht vermasseln<\/h2>\n<p>Es gibt keine zweite Chance f\u00fcr einen ersten Eindruck, sagt ein Sprichwort. Leider ist das wirklich so. Hat der Bewerber nur wenige Minuten Pr\u00e4sentationszeit, kann er einen anf\u00e4nglichen Faux Pas nicht mehr ausb\u00fcgeln. \u201e<em>Nach einem schlechten ersten Eindruck braucht es Zeit, um das wieder hinzukriegen<\/em>\u201c, wei\u00df Flume. Eine anschlie\u00dfende erfolgreiche Zusammenarbeit etwa.<\/p>\n<hr \/>\n<p><em>Gastbeitrag von Pflegebibel.de<\/em><\/p>\n<div style=\"text-align:center\" class=\"yasr-auto-insert-visitor\"><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_4295' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-4295\"> Beitrag bewerten<\/div><div id='yasr-vv-second-row-container-f3ab360a46f43' \n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-f3ab360a46f43'\n                                      class='yasr-rater-stars-vv'\n                                      data-rater-postid='4295' \n                                      data-rating='0'\n                                      data-rater-starsize='24'\n                                      data-rater-readonly='false'\n                                      data-rater-nonce='319d52f732' \n                                      data-issingular='false'\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-f3ab360a46f43\"><span id=\"yasr-vv-text-container-f3ab360a46f43\" class=\"yasr-vv-text-container\"> <span id=\"yasr-vv-votes-number-container-f3ab360a46f43\">0<\/span> Bewertungen<\/span><\/div><div id='yasr-vv-loader-f3ab360a46f43' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-f3ab360a46f43' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Bis zu 95 Prozent unserer Glaubw\u00fcrdigkeit macht die K\u00f6rpersprache aus: Gestik und Haltung entscheiden nicht nur \u00fcber den ersten Eindruck im privaten Aufeinandertreffen &#8211; man sollte auch auf die K\u00f6rpersprache im Bewerbungsgespr\u00e4ch achten. Und nur wer seinen Inhalten positiv gegen\u00fcbersteht, kann diese auch \u00fcberzeugend pr\u00e4sentieren. Mit diesen K\u00f6rpersprache-Tricks rockt man als Bewerber das Vorstellungsgespr\u00e4ch. Positive<\/p>\n","protected":false},"author":28,"featured_media":4297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":""},"categories":[1],"tags":[111,115,301,302,84],"yst_prominent_words":[3019,355,416,748,746,2856,3015,981,3012,3018,985,3010,3013,3016,513,3011,3017,629,3014,2021],"yasr_visitor_votes":{"number_of_votes":0,"sum_votes":0,"stars_attributes":{"read_only":false,"span_bottom":false}},"_links":{"self":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/4295"}],"collection":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/comments?post=4295"}],"version-history":[{"count":6,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/4295\/revisions"}],"predecessor-version":[{"id":10240,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/4295\/revisions\/10240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media\/4297"}],"wp:attachment":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media?parent=4295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/categories?post=4295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/tags?post=4295"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/yst_prominent_words?post=4295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}