{"id":429,"date":"2019-09-12T17:13:16","date_gmt":"2019-09-12T15:13:16","guid":{"rendered":"http:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/?p=429"},"modified":"2019-12-05T13:04:02","modified_gmt":"2019-12-05T11:04:02","slug":"job-finden","status":"publish","type":"post","link":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/job-finden\/","title":{"rendered":"5 Wege, wie erfolgreiche Menschen einen Job finden"},"content":{"rendered":"<p>Erfolgreiche Menschen finden eher eine neue Stelle, weil sie schon erfolgreich sind. Zu dem Schluss k\u00f6nnte man schnell kommen. Einen guten <strong>Job finden<\/strong>? Nat\u00fcrlich greifen sie h\u00e4ufig auf wertvolle Kontakte zur\u00fcck, die die Suche nach einer neuen Herausforderung erleichtern k\u00f6nnen. Doch sie ber\u00fccksichtigen neben dem <strong>Netzwerk<\/strong> weitere Strategien, die die <strong>Stellensuche<\/strong> zu einem Erfolg werden lassen. Was kann man sich davon f\u00fcr die eigene Jobsuche abschauen?<\/p>\n<h2>1. Im Netzwerk\u00a0den gesuchten Job finden<\/h2>\n<p>Insbesondere Kandidaten, die nicht aktiv auf Jobsuche sind, bringen oft erst einmal in ihrem Freundes- und Bekanntenkreis und im beruflichen Umfeld in Erfahrung, welche Perspektiven sich ihnen derzeit bieten. Nicht ohne Grund: Das Institut f\u00fcr Arbeitsmarkt- und Berufsforschung hat beispielsweise herausgefunden, dass 40 Prozent der freien Stellen \u00fcber Beziehungen vergeben werden. Eine Studie der EU-Kommission belegt sogar, dass es unter F\u00fchrungspositionen 70 Prozent sind.<\/p>\n<blockquote><p>Gerade im professionellen Netzwerk gilt allerdings, nicht direkt mit der T\u00fcr ins Haus zu fallen mit der Frage \u201cNa, hast du vielleicht einen Job f\u00fcr mich?\u201d. Vielmehr geht es darum herauszufinden, vor welchen Herausforderungen ein Unternehmen, eine Abteilung oder ein Team gerade steht und ob du mit deinem Profil und deinen Ideen zur L\u00f6sung von Problemen beitragen k\u00f6nntest.<\/p><\/blockquote>\n<h2>2. Information ist das A und O<\/h2>\n<p>Neben dem Aktivieren des eigenen Netzwerks, um Jobchancen auszumachen, setzen erfolgreiche Menschen auf informierte Karriereentscheidungen. Bevor sie sich f\u00fcr eine neue Stelle oder ein bestimmtes Unternehmen entscheiden, versuchen sie so viel wie m\u00f6glich dar\u00fcber in Erfahrung zu bringen. Sie treffen sich mit ihren Kontakten im Umfeld des Unternehmens, betreiben eigene Recherche \u00fcber die Stelle, die Firma und m\u00f6gliche neue Kollegen und diskutieren mit Freunden und Verwandten Vor- und Nachteile der neuen Position. Auf diese Weise stellt man sicher, dass man \u00fcber das Netzwerk nicht an irgendeinen Job kommt, sondern eine Stelle\u00a0findet, die wirklich passt.<\/p>\n<h2>3. \u201cWas w\u00e4ren\u00a0die Aufgaben?\u201d statt \u201cWas steht in der Stellenausschreibung?\u201d<\/h2>\n<p>W\u00e4hrend die meisten Stellensuchenden sich an den Jobausschreibungen abarbeiten, bringen erfolgreiche Menschen in Erfahrung, welche Aufgaben tats\u00e4chlich in den jeweiligen Verantwortungsbereich fallen. Nicht selten enthalten Ausschreibungen viele allgemeine Angaben, aber wenig konkrete Aussagen zum tats\u00e4chlichen Arbeitsbereich oder den zu bearbeitenden Projekten. Wer einen Job finden will, muss genau hinschauen!<\/p>\n<p>Wer einen pers\u00f6nlichen Kontakt im Unternehmen oder im Team hat, kommt nat\u00fcrlich schnell an diese Informationen. Doch auch ohne Informanten lassen sich diese Dinge aufdecken. Vor der Bewerbung in der Personalabteilung nachfragen oder &#8211; falls dort niemand Auskunft geben kann oder m\u00f6chte &#8211; im Vorstellungsgespr\u00e4ch auf diese Punkte eingehen.<\/p>\n<blockquote><p>Das hinterl\u00e4sst auch bei dem Interviewpartner den positiven Eindruck, dass man sich intensiv mit der ausgeschriebenen Position auseinandersetzen m\u00f6chte.<\/p><\/blockquote>\n<h2>4. T\u00e4tigkeiten und Entwicklungschancen vor Verg\u00fctung<\/h2>\n<p>Informationen \u00fcber konkrete Aufgabenfelder, aber auch berufliche Perspektiven und Weiterentwicklungsm\u00f6glichkeiten im Unternehmen sind wichtige Elemente bei der \u00dcberlegung, ob eine Stelle f\u00fcr dich in Betracht kommt. Erfolgreiche Menschen suchen nach der n\u00e4chsten Herausforderung, die sie beruflich und pers\u00f6nlich weiterbringt &#8211; nicht zwingend nach den besten Verdienstm\u00f6glichkeiten.<\/p>\n<p>Man sollte also herausfinden,\u00a0was eine neue Position dahingehend bietet. F\u00fcr Berufseinsteiger kann es beispielsweise sinnvoll sein, sich f\u00fcr den geringer bezahlten Startup-Job (und gegen die hochdotierte Konzernstelle) zu entscheiden. Dort wird man fr\u00fch eigenverantwortlich arbeiten und so wertvolle Berufserfahrung sammeln k\u00f6nnen.<\/p>\n<h2>5. Finanzieller Druck sollte nicht den Ausschlag geben<\/h2>\n<p>Wer beruflich erfolgreich ist, entscheidet sich meist nicht aus \u00f6konomischen Druck f\u00fcr eine neue Stelle. Das ist nat\u00fcrlich keine \u00dcberraschung: Erfolgreiche Menschen d\u00fcrften bereits ein ordentliches Einkommen haben. Allerdings l\u00e4sst sich hieraus dennoch ein Tipp ableiten, den man ber\u00fccksichtigen kann. Die Entscheidung f\u00fcr eine neue Stelle sollte wohl\u00fcberlegt und abgewogen, statt aus einer Notsituation heraus gef\u00e4llt sein.<br \/>\nNat\u00fcrlich ist das leichter gesagt als getan, wenn man nicht wei\u00df, wie man am Ende des Monats seine Rechnungen bezahlen soll. In diesem Fall kann es ratsam sein, erst einmal rasch einen Job anzunehmen und die Stellensuche von dort aus ohne finanzielle N\u00f6te noch einmal anzugehen.<\/p>\n<h2>Fazit:<\/h2>\n<p>Bei <a href=\"https:\/\/jobspotting.com\/de\" target=\"_blank\" rel=\"noopener noreferrer\">Jobspotting<\/a> m\u00f6chten\u00a0man dem Bewerber das ideale Umfeld bieten, um eine \u00fcberlegte und informierte Karriereentscheidung zu treffen. Hier werden Stellen vorgeschlagen,\u00a0die den F\u00e4higkeiten, Kenntnissen und Erfahrungen entsprechen. Au\u00dferdem werden Unternehmens- und Einstellungstrends geliefert und detaillierte Informationen \u00fcber potenzielle Arbeitgeber, Mitbewerber und die Arbeitsmarktsituation geboten. So kann man ganz leicht einen neuen Job finden.<\/p>\n<div style=\"text-align:center\" class=\"yasr-auto-insert-visitor\"><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_429' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-429\"> Beitrag bewerten<\/div><div id='yasr-vv-second-row-container-eb3063054a401' \n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-eb3063054a401'\n                                      class='yasr-rater-stars-vv'\n                                      data-rater-postid='429' \n                                      data-rating='0'\n                                      data-rater-starsize='24'\n                                      data-rater-readonly='false'\n                                      data-rater-nonce='319d52f732' \n                                      data-issingular='false'\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-eb3063054a401\"><span id=\"yasr-vv-text-container-eb3063054a401\" class=\"yasr-vv-text-container\"> <span id=\"yasr-vv-votes-number-container-eb3063054a401\">0<\/span> Bewertungen<\/span><\/div><div id='yasr-vv-loader-eb3063054a401' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-eb3063054a401' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Erfolgreiche Menschen finden eher eine neue Stelle, weil sie schon erfolgreich sind. Zu dem Schluss k\u00f6nnte man schnell kommen. Einen guten Job finden? Nat\u00fcrlich greifen sie h\u00e4ufig auf wertvolle Kontakte zur\u00fcck, die die Suche nach einer neuen Herausforderung erleichtern k\u00f6nnen. Doch sie ber\u00fccksichtigen neben dem Netzwerk weitere Strategien, die die Stellensuche zu einem Erfolg werden<\/p>\n","protected":false},"author":28,"featured_media":431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":""},"categories":[1],"tags":[182,45],"yst_prominent_words":[1960,404,494,905,1956,1835,874,401,1955,789,970,854,1954,3778,1958,411,672,1957,396,1959],"yasr_visitor_votes":{"number_of_votes":0,"sum_votes":0,"stars_attributes":{"read_only":false,"span_bottom":false}},"_links":{"self":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/429"}],"collection":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":10,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"predecessor-version":[{"id":9696,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/429\/revisions\/9696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media\/431"}],"wp:attachment":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/categories?post=429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/tags?post=429"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/yst_prominent_words?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}