{"id":365,"date":"2019-08-28T15:02:23","date_gmt":"2019-08-28T13:02:23","guid":{"rendered":"http:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/?p=365"},"modified":"2019-12-05T12:42:30","modified_gmt":"2019-12-05T10:42:30","slug":"bewerbung-fehler","status":"publish","type":"post","link":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/bewerbung-fehler\/","title":{"rendered":"5 Gr\u00fcnde, weshalb die Bewerbung sofort aussortiert wird"},"content":{"rendered":"<p>Bewerbungen schreiben f\u00e4llt vielen Menschen schwer. Es nimmt kostbare Zeit in Anspruch, man muss viele Informationen in relativ wenig Text packen und es verlangt ein hohes Ma\u00df an Kreativit\u00e4t. Sehr \u00e4rgerlich ist es, wenn der erw\u00fcnschte Erfolg dann am Ende sogar noch ausbleibt. Doch woran liegt das? Schlie\u00dflich hat man versucht, sein Bestes zu geben und alles richtig zu machen. Leider schleichen sich schnell kleine, aber feine Fehler ein, die keinem Personaler gefallen.\u00a0Hier sind 5 schwerwiegende Fehler aufgelistet, die man auf alle F\u00e4lle vermeiden sollte &#8211; ansonsten landet die Bewerbung direkt im M\u00fcll.<\/p>\n<h2>1. Rechtschreib-, Grammatik- und Kommafehler<\/h2>\n<p>Dieser Punkt sollte selbstverst\u00e4ndlich sein. Eine Bewerbung, die &#8211; wenn auch nur wenige &#8211; Rechtschreib-, Grammatik- oder Kommafehler aufweist, wird sofort aussortiert. Dadurch vermittelt man nicht nur ein fehlendes Sprachgef\u00fchl, sondern auch einen Eindruck von Ungenauigkeit. Deshalb sollte man seine Bewerbungsunterlagen in jedem Fall \u00fcberpr\u00fcfen lassen. Oder man vermeidet solche Fehler von vornherein, indem man sich seine <a href=\"http:\/\/www.richtiggutbewerben.de\/?schlechtebewerbung\">Unterlagen professionell erstellen<\/a> l\u00e4sst.<\/p>\n<h2>2. Kein Bezug zum Unternehmen<\/h2>\n<p>Selbst wenn man der perfekte Kandidat f\u00fcr die ausgeschriebene Stelle ist, wird der potenzielle Arbeitgeber sich nicht f\u00fcr einen interessieren, wenn man keinen Bezug zum Unternehmen herstellt. Mit Teamf\u00e4higkeit und Zuverl\u00e4ssigkeit bei der Arbeit m\u00f6chte jeder \u00fcberzeugen. Aber nur der Bewerber kann \u00fcberzeugen, der seine F\u00e4higkeiten mit den Anforderungen des Unternehmens in Verbindung bringen kann.<\/p>\n<blockquote><p>Au\u00dferdem sollte man dem potenziellen Arbeitgeber zeigen, dass man sich ausf\u00fchrlich \u00fcber das Unternehmen informiert hat und der geeignete Kandidat f\u00fcr die Stelle ist. Deshalb sollte man sich vorab \u00fcber das Unternehmen schlau machen und schauen, welche Anforderungen an die Bewerber gestellt werden. Durch den Bezug zum Unternehmen wird die Bewerbung pers\u00f6nlicher und zeugt von ernsthaftem Interesse an der Stelle, um die man sich bewirbt.<\/p><\/blockquote>\n<h2>3. Nicht an den richtigen Ansprechpartner gerichtet<\/h2>\n<p>Im Rahmen der Recherche ist es zudem besonders wichtig, den richtigen Ansprechpartner ausfindig zu machen. Klingt einfach, ist es aber nicht unbedingt. Oft ist der Ansprechpartner bei der Stellenausschreibung mit angegeben. Manchmal erfordert es aber auch ein paar Klicks, um zu wissen, an wen man die Bewerbung richten soll. Diese M\u00fche sollte man sich auf jeden Fall machen, da es nicht nur peinlich w\u00e4re, den falschen oder keinen Ansprechpartner anzugeben, sondern auch zeigt, dass man sich nicht richtig informiert hat.<\/p>\n<h2>4. \u00dcberladenes Design in der Bewerbung<\/h2>\n<p>Ein <a href=\"http:\/\/www.richtiggutbewerben.de\/Bewerbungsvorlage\/index.html\">ansprechendes Design<\/a> ist wichtig. Da bei den Personalern viele Bewerbungen auf dem Tisch landen, muss es zudem auch mal ausgefallener sein. Aber Vorsicht: Ein zu \u00fcberladenes oder unstimmiges Design wirkt abschreckend und unprofessionell! Gerne kann man durch Farben, Bullet Points und klare Abschnitte die Bewerbung ansprechend gestalten. Allerdings sollte man nicht mit unterschiedlichen und unseri\u00f6sen Schrifttypen herum experimentieren, buntes Papier benutzen oder mit verspielten Effekten arbeiten &#8211; das wirkt unprofessionell und lenkt vom Wesentlichen ab. Das Design sollte den Inhalt unterst\u00fctzen, nicht irritieren oder abschrecken.<\/p>\n<h2>5. Es wimmelt nur so von Standardformulierungen<\/h2>\n<p>&#8222;Mit gro\u00dfem Interesse habe ich Ihre Stellenausschreibung gelesen&#8230;&#8220; oder &#8222;Da ihr Anforderungsprofil genau meinen F\u00e4higkeiten und Neigungen entspricht, sehe ich mich als perfekten Kandidaten f\u00fcr Ihre Stellenausschreibung&#8220; &#8211; solche und weitere\u00a0 Standardformulierungen sind nicht nur \u00fcberfl\u00fcssig und inhaltslos, sondern \u00fcberzeugen auch keinen Personaler.<\/p>\n<blockquote><p>Leere Phrasen und endlose Auflistungen von Soft Skills, ohne diese mit Hard Facts in Verbindung zu bringen, sollten vermieden werden. Teamf\u00e4hig und zuverl\u00e4ssig ist laut Bewerbung jeder &#8211; aber wie und wo hat man sich diese F\u00e4higkeiten angeeignet?<\/p><\/blockquote>\n<p>Das K\u00f6nnen und Wissen sollte mit den Anforderungen des Unternehmens sowie mit der Unternehmenskultur\u00a0verkn\u00fcpft werden &#8211; da ist auch wieder eine ausf\u00fchrliche Recherche gefragt. Wer Schwierigkeiten dabei hat, kann sich auch <a href=\"http:\/\/richtiggutbewerben.de\/?schlechtebewerbung\">professionelle Bewerbungsunterlagen erstellen lassen<\/a>, die individuell, ansprechend und professionell sind.<\/p>\n<h2>Fazit:<\/h2>\n<p>Beim Bewerbungen schreiben schleichen sich schnell kleine Fehler mit gro\u00dfer Wirkung ein &#8211; leider zum Nachteil des Bewerbers. Ein <a href=\"http:\/\/richtiggutbewerben.de\/?schlechtebewerbung\">professioneller Bewerbungsservice<\/a> kann helfen, diese Fehler zu vermeiden, die Bewerbung ansprechend zu gestalten und dem Kandidaten mit einem individuellen Anschreiben zu erm\u00f6glichen, sich gegen die anderen Bewerber durchzusetzen.<\/p>\n<div style=\"text-align:center\" class=\"yasr-auto-insert-visitor\"><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_365' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-365\"> Beitrag bewerten<\/div><div id='yasr-vv-second-row-container-caf90693afad5' \n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-caf90693afad5'\n                                      class='yasr-rater-stars-vv'\n                                      data-rater-postid='365' \n                                      data-rating='0'\n                                      data-rater-starsize='24'\n                                      data-rater-readonly='false'\n                                      data-rater-nonce='319d52f732' \n                                      data-issingular='false'\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-caf90693afad5\"><span id=\"yasr-vv-text-container-caf90693afad5\" class=\"yasr-vv-text-container\"> <span id=\"yasr-vv-votes-number-container-caf90693afad5\">0<\/span> Bewertungen<\/span><\/div><div id='yasr-vv-loader-caf90693afad5' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-caf90693afad5' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Bewerbungen schreiben f\u00e4llt vielen Menschen schwer. Es nimmt kostbare Zeit in Anspruch, man muss viele Informationen in relativ wenig Text packen und es verlangt ein hohes Ma\u00df an Kreativit\u00e4t. Sehr \u00e4rgerlich ist es, wenn der erw\u00fcnschte Erfolg dann am Ende sogar noch ausbleibt. Doch woran liegt das? Schlie\u00dflich hat man versucht, sein Bestes zu geben<\/p>\n","protected":false},"author":28,"featured_media":372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":""},"categories":[1],"tags":[193,135],"yst_prominent_words":[1749,1823,3771,1317,355,342,1825,482,1824,835,881,437,778,483,1821,1604,411,1013,1754,396],"yasr_visitor_votes":{"number_of_votes":0,"sum_votes":0,"stars_attributes":{"read_only":false,"span_bottom":false}},"_links":{"self":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/365"}],"collection":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/comments?post=365"}],"version-history":[{"count":14,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/365\/revisions"}],"predecessor-version":[{"id":9671,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/posts\/365\/revisions\/9671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media\/372"}],"wp:attachment":[{"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/media?parent=365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/categories?post=365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/tags?post=365"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/richtiggutbewerben.de\/Bewerbungstipps\/Bewerbungsblog\/wp-json\/wp\/v2\/yst_prominent_words?post=365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}